{"id":4823,"date":"2023-05-26T12:18:09","date_gmt":"2023-05-26T12:18:09","guid":{"rendered":"https:\/\/www.cadelbosco.com\/?post_type=wines-info&#038;p=4823"},"modified":"2023-05-26T12:18:09","modified_gmt":"2023-05-26T12:18:09","slug":"vintage-collection-dosage-zero-1999","status":"publish","type":"wines-info","link":"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999","title":{"rendered":"Vintage Collection Dosage Z\u00e9ro 1999"},"template":"","class_list":["post-4823","wines-info","type-wines-info","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vintage Collection Dosage Z\u00e9ro 1999 | Ca&#039; Del Bosco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vintage Collection Dosage Z\u00e9ro 1999 | Ca&#039; Del Bosco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999\" \/>\n<meta property=\"og:site_name\" content=\"Ca&#039; Del Bosco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CaDelBosco\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cadelbosco.com\/wp-content\/uploads\/2022\/10\/image_2022-10-11_130118493.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cadelboscoita\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/en\\\/?wines-info=vintage-collection-dosage-zero-1999\",\"url\":\"https:\\\/\\\/www.cadelbosco.com\\\/en\\\/?wines-info=vintage-collection-dosage-zero-1999\",\"name\":\"Vintage Collection Dosage Z\u00e9ro 1999 | Ca&#039; Del Bosco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/#website\"},\"datePublished\":\"2023-05-26T12:18:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/en\\\/?wines-info=vintage-collection-dosage-zero-1999#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cadelbosco.com\\\/en\\\/?wines-info=vintage-collection-dosage-zero-1999\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/en\\\/?wines-info=vintage-collection-dosage-zero-1999#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cadelbosco.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vintage Collection Dosage Z\u00e9ro 1999\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/\",\"name\":\"Ca&#039; Del Bosco\",\"description\":\"Franciacorta e vini\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/#organization\",\"name\":\"Ca' del Bosco\",\"url\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cadelbosco.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/6_epNQsa_400x400.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.cadelbosco.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/6_epNQsa_400x400.jpeg\",\"width\":400,\"height\":400,\"caption\":\"Ca' del Bosco\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadelbosco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CaDelBosco\",\"https:\\\/\\\/x.com\\\/cadelboscoita\",\"https:\\\/\\\/www.instagram.com\\\/cadelbosco_official\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vintage Collection Dosage Z\u00e9ro 1999 | Ca&#039; Del Bosco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999","og_locale":"en_US","og_type":"article","og_title":"Vintage Collection Dosage Z\u00e9ro 1999 | Ca&#039; Del Bosco","og_url":"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999","og_site_name":"Ca&#039; Del Bosco","article_publisher":"https:\/\/www.facebook.com\/CaDelBosco","og_image":[{"width":1600,"height":750,"url":"https:\/\/www.cadelbosco.com\/wp-content\/uploads\/2022\/10\/image_2022-10-11_130118493.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@cadelboscoita","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999","url":"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999","name":"Vintage Collection Dosage Z\u00e9ro 1999 | Ca&#039; Del Bosco","isPartOf":{"@id":"https:\/\/www.cadelbosco.com\/it\/#website"},"datePublished":"2023-05-26T12:18:09+00:00","breadcrumb":{"@id":"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadelbosco.com\/en\/?wines-info=vintage-collection-dosage-zero-1999#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadelbosco.com\/en\/"},{"@type":"ListItem","position":2,"name":"Vintage Collection Dosage Z\u00e9ro 1999"}]},{"@type":"WebSite","@id":"https:\/\/www.cadelbosco.com\/it\/#website","url":"https:\/\/www.cadelbosco.com\/it\/","name":"Ca&#039; Del Bosco","description":"Franciacorta e vini","publisher":{"@id":"https:\/\/www.cadelbosco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadelbosco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cadelbosco.com\/it\/#organization","name":"Ca' del Bosco","url":"https:\/\/www.cadelbosco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cadelbosco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.cadelbosco.com\/wp-content\/uploads\/2022\/10\/6_epNQsa_400x400.jpeg","contentUrl":"https:\/\/www.cadelbosco.com\/wp-content\/uploads\/2022\/10\/6_epNQsa_400x400.jpeg","width":400,"height":400,"caption":"Ca' del Bosco"},"image":{"@id":"https:\/\/www.cadelbosco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CaDelBosco","https:\/\/x.com\/cadelboscoita","https:\/\/www.instagram.com\/cadelbosco_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cadelbosco.com\/en\/wp-json\/wp\/v2\/wines-info\/4823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadelbosco.com\/en\/wp-json\/wp\/v2\/wines-info"}],"about":[{"href":"https:\/\/www.cadelbosco.com\/en\/wp-json\/wp\/v2\/types\/wines-info"}],"wp:attachment":[{"href":"https:\/\/www.cadelbosco.com\/en\/wp-json\/wp\/v2\/media?parent=4823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}